{"id":2456,"date":"2022-03-08T15:28:41","date_gmt":"2022-03-08T14:28:41","guid":{"rendered":"https:\/\/www.kitchen.fr\/blog\/?p=2456"},"modified":"2022-03-10T16:37:27","modified_gmt":"2022-03-10T15:37:27","slug":"poele-acier-mineral-b","status":"publish","type":"post","link":"https:\/\/www.kitchen.fr\/blog\/poele-acier-mineral-b\/","title":{"rendered":"Tout savoir sur les po\u00eales en acier MINERAL B"},"content":{"rendered":"<p>Quels sont les sp\u00e9cificit\u00e9s de la gamme MINERAL B\u00a0? Kitchen.fr est l\u00e0 pour r\u00e9pondre \u00e0 cette question !<\/p>\n<p>Tout d\u2019abord, sachez que ces po\u00eales sont fabriqu\u00e9es avec de la<strong> t\u00f4le d\u2019acier 100% naturel<\/strong> avec 99% de fer. Elles sont donc indestructibles !<\/p>\n<p>Plus souvent appel\u00e9e po\u00eale en fer, elle est le type de po\u00eale le plus simple\u00a0: c\u2019est la po\u00eale de nos grands-m\u00e8res et grands-p\u00e8res.<\/p>\n<p>La conductivit\u00e9 thermique du fer permet \u00e0 cet ustensile de monter rapidement en temp\u00e9rature, ce qui le rend id\u00e9al pour saisir une viande ou encore dorer vos aliments.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2458\" aria-describedby=\"caption-attachment-2458\" style=\"width: 387px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2458\" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977.jpeg\" alt=\"\" width=\"387\" height=\"445\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977.jpeg 1652w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977-890x1024.jpeg 890w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977-768x884.jpeg 768w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977-1335x1536.jpeg 1335w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977-435x500.jpeg 435w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0977-1130x1300.jpeg 1130w\" sizes=\"(max-width: 387px) 100vw, 387px\" \/><figcaption id=\"caption-attachment-2458\" class=\"wp-caption-text\">Po\u00eale MINERAL B<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Pourquoi choisir les po\u00eales De Buyer MINERAL B ?<\/h2>\n<h3>Avantages MINERAL B<\/h3>\n<p>Les po\u00eale en acier ont de nombreux avantages. Voici une petite liste pour vous r\u00e9pertorier tout cela\u00a0:<\/p>\n<ul>\n<li>Finition \u00e0 la cire d&rsquo;abeille fran\u00e7aise pour une protection naturelle contre l&rsquo;oxydation et faciliter le <strong>culottage<\/strong> qui est le traitement de surface des ustensiles de cuisine m\u00e9talliques avec de la graisse ou de l&rsquo;huile chauff\u00e9e afin de produire un rev\u00eatement r\u00e9sistant \u00e0 la corrosion et \u00e0 l&rsquo;adh\u00e9sion des aliments.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Faciliter la <strong>r\u00e9action de Maillard <\/strong>provoquer lorsque la po\u00eale en t\u00f4le d&rsquo;acier atteint des temp\u00e9ratures sup\u00e9rieures \u00e0 140 \u00b0C. Les aliments sont saisis en surface, permettant ainsi la caram\u00e9lisation de leurs sucs naturels. Les aliments deviennent dor\u00e9s et croustillants en surface mais fondants et moelleux \u00e0 l\u2019int\u00e9rieur\u2026<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>T\u00f4le d&rsquo;acier blanche 100% naturelle de 3mm d&rsquo;\u00e9paisseur, ind\u00e9formable m\u00eame sur induction.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Garantie \u00e0 vie.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Elle obtient son anti-adh\u00e9rence naturellement avec le temps car plus la po\u00eale est utilis\u00e9e, plus elle se culotte et moins elle attache.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Coupe lyonnaise<\/strong> \u00e9vas\u00e9e et bomb\u00e9e a un bord haut pour favoriser la glisse des aliments dans la po\u00eale.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Queue feuillard<\/strong> qui est une courbure \u00e0 la fran\u00e7aise\u00a0et qui permet une manipulation facile et une pr\u00e9hension ergonomique. Sa courbure \u00e9loigne la main de la source de chaleur et permet de mieux r\u00e9partir le poids.<\/li>\n<\/ul>\n<figure id=\"attachment_2461\" aria-describedby=\"caption-attachment-2461\" style=\"width: 602px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2461\" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/mineral-b.png\" alt=\"\" width=\"602\" height=\"263\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/mineral-b.png 739w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/mineral-b-500x219.png 500w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><figcaption id=\"caption-attachment-2461\" class=\"wp-caption-text\">Sch\u00e9ma po\u00eale en acier<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_2459\" aria-describedby=\"caption-attachment-2459\" style=\"width: 419px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2459 \" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966.jpeg\" alt=\"\" width=\"419\" height=\"314\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966.jpeg 2048w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966-1024x768.jpeg 1024w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966-768x576.jpeg 768w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966-1536x1152.jpeg 1536w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966-500x375.jpeg 500w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0966-1300x975.jpeg 1300w\" sizes=\"(max-width: 419px) 100vw, 419px\" \/><figcaption id=\"caption-attachment-2459\" class=\"wp-caption-text\">Queue po\u00eale MINERAL B<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Information induction\u00a0:<\/p>\n<p>Le fer est un mat\u00e9riau r\u00e9actif, hyper <strong>conducteur de chaleur<\/strong>. L\u2019induction a une puissance de chauffe tr\u00e8s importante. C\u2019est pourquoi, pour une utilisation de la po\u00eale en acier sur induction nous vous conseillons\u00a0:<\/p>\n<ul>\n<li>D\u2019utiliser une temp\u00e9rature mod\u00e9r\u00e9e<\/li>\n<li>De ne pas utiliser le BOOSTER<\/li>\n<li>De ne pas surchauffer la po\u00eale en fer \u00e0 vide<\/li>\n<\/ul>\n<figure id=\"attachment_2460\" aria-describedby=\"caption-attachment-2460\" style=\"width: 386px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2460\" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981.jpeg\" alt=\"\" width=\"386\" height=\"515\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981.jpeg 1536w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981-768x1024.jpeg 768w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981-1152x1536.jpeg 1152w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981-375x500.jpeg 375w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0981-975x1300.jpeg 975w\" sizes=\"(max-width: 386px) 100vw, 386px\" \/><figcaption id=\"caption-attachment-2460\" class=\"wp-caption-text\">Po\u00eale De Buyer<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h3>Pourquoi \u00ab\u00a0B\u00a0\u00bb dans MINERAL B\u00a0?<\/h3>\n<p>Et bien\u2026 c\u2019est B comme \u00ab\u00a0bee \u00bb (Abeille en anglais)<\/p>\n<p>L&rsquo;abeille repr\u00e9sente la vie et ses productions poss\u00e8dent de grandes vertus naturelles.<\/p>\n<p>La cire d&rsquo;abeille est apte au contact alimentaire. Elle \u00e9tait utilis\u00e9e autrefois en cuisine comme protection des ustensiles en <strong>fer blanc<\/strong> et cuivre \u00e9tame.<\/p>\n<p>Depuis 2011, celle-ci prot\u00e8ge les ustensiles de la gamme MINERAL B contre l&rsquo;oxydation.<\/p>\n<p>En 2018, des ruches ont \u00e9t\u00e9 install\u00e9s sur le site industriel au Val d&rsquo;Ajol.<\/p>\n<p>Vous trouverez d\u2019ailleurs, une petite abeille avec la lettre \u00ab\u00a0B\u00a0\u00bb grav\u00e9e dans votre ustensile de cuisine.<\/p>\n<figure id=\"attachment_2463\" aria-describedby=\"caption-attachment-2463\" style=\"width: 305px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2463\" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962.jpeg\" alt=\"\" width=\"305\" height=\"407\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962.jpeg 1536w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962-768x1024.jpeg 768w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962-1152x1536.jpeg 1152w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962-375x500.jpeg 375w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0962-975x1300.jpeg 975w\" sizes=\"(max-width: 305px) 100vw, 305px\" \/><figcaption id=\"caption-attachment-2463\" class=\"wp-caption-text\">Fond des po\u00eale MINERAL B<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2>Culottage\u00a0et entretien<\/h2>\n<h3>Comment culotter ce mat\u00e9riel de cuisine en acier\u00a0?<\/h3>\n<p>\u00c0 la r\u00e9ception, la po\u00eale est d&rsquo;un aspect lisse et argent\u00e9. Gr\u00e2ce \u00e0 son rev\u00eatement \u00e0 la cire d&rsquo;abeille fran\u00e7aise, elle r\u00e9siste \u00e0 l&rsquo;oxydation.<\/p>\n<figure id=\"attachment_2464\" aria-describedby=\"caption-attachment-2464\" style=\"width: 414px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2464\" src=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967.jpeg\" alt=\"\" width=\"414\" height=\"311\" srcset=\"https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967.jpeg 2048w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967-1024x768.jpeg 1024w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967-768x576.jpeg 768w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967-1536x1152.jpeg 1536w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967-500x375.jpeg 500w, https:\/\/www.kitchen.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_0967-1300x975.jpeg 1300w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/><figcaption id=\"caption-attachment-2464\" class=\"wp-caption-text\">Grill MINERAL B<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Il faut alors proc\u00e9der au culottage de la po\u00eale avant la premi\u00e8re utilisation pour b\u00e9n\u00e9ficier de son <strong>anti-adh\u00e9rence naturelle<\/strong>.<\/p>\n<ol>\n<li>Laver \u00e0 l\u2019eau tr\u00e8s chaude avec du savon, puis rincer et s\u00e9cher<\/li>\n<li>Faites chauffer \u00e0 feu moyen environ 1 cm d\u2019huile pendant 5 minutes<\/li>\n<li>Retirer l\u2019huile et essuyer avec du papier absorbant.<\/li>\n<\/ol>\n<p>La po\u00eale MINERAL B est sans aucun rev\u00eatement et cette caract\u00e9ristique pr\u00e9sente deux avantages\u00a0:<\/p>\n<ul>\n<li>Garantie de pouvoir d\u00e9glacer puis flamber sans risque les viandes et de r\u00e9cup\u00e9rer les sucs de cuisson.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>R\u00e9aliser la fameuse r\u00e9action de Maillard. Cette r\u00e9action se produit au moment de la cuisson des aliments et permet de mieux en r\u00e9v\u00e9ler l\u2019ensemble des ar\u00f4mes.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3>Entretien de la MINERAL B<\/h3>\n<p>Apr\u00e8s le culottage et au fur et \u00e0 mesure des utilisations, <strong>l&rsquo;ustensile en acier<\/strong> se culotte : sa couleur va changer (bleuir, noircir ou vernir). Cette r\u00e9action est tout \u00e0 fait normale\u00a0! Elle assure l&rsquo;anti-adh\u00e9rence de la po\u00eale.<\/p>\n<p>Elle se bonifiera avec le temps car plus elle est utilis\u00e9e, plus elle se culotte et moins elle attache.<\/p>\n<p>Pour la nettoyer, d\u00e9glacer la avec de l\u2019eau froide apr\u00e8s chaque utilisation puis laver \u00e0 la main. Bien essuyer avec du papier absorbant.<\/p>\n<p>Que faire si\u00a0:<\/p>\n<ul>\n<li>La po\u00eale rouille\u00a0: frotter avec une brosse dure<\/li>\n<li>Des taches blanches apparaissent \u00e0 cause de l\u2019acidit\u00e9 de certains aliments\u00a0: refaites un culottage<\/li>\n<li>Le mat\u00e9riel a besoin d\u2019\u00eatre purifi\u00e9\u00a0: chauffer du gros sel environ 1 minute 30 \u00e0 feu vif et essuyer, puis huiler.<\/li>\n<\/ul>\n<p>Attention\u00a0! Ne pas laisser tremper ni mettre au lave-vaisselle.<\/p>\n<p>&nbsp;<\/p>\n<p>Vous l&rsquo;aurez compris, si vous avez envie de retrouver les saveurs de la cuisson de vos grands-m\u00e8res, avec un investissement sur le long terme (\u00e0 condition de respecter les r\u00e8gles d&rsquo;utilisation et d&rsquo;entretien), optez pour la gamme MINERAL B de chez De Buyer\u00a0!<\/p>\n<p>Si vous avez la moindre question\u00a0: n\u2019h\u00e9sitez pas, Kitchen.fr vous r\u00e9pondra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quels sont les sp\u00e9cificit\u00e9s de la gamme MINERAL B\u00a0? Kitchen.fr est l\u00e0 pour r\u00e9pondre \u00e0 cette question ! Tout d\u2019abord, sachez que ces po\u00eales sont fabriqu\u00e9es avec de la t\u00f4le d\u2019acier 100% naturel avec 99% de fer. Elles sont donc indestructibles ! Plus souvent appel\u00e9e po\u00eale en fer, elle est le type de po\u00eale le&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.kitchen.fr\/blog\/poele-acier-mineral-b\/\">Lire plus<\/a><\/div>\n","protected":false},"author":1,"featured_media":2470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/posts\/2456"}],"collection":[{"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/comments?post=2456"}],"version-history":[{"count":7,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/posts\/2456\/revisions"}],"predecessor-version":[{"id":2472,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/posts\/2456\/revisions\/2472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/media\/2470"}],"wp:attachment":[{"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/media?parent=2456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/categories?post=2456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kitchen.fr\/blog\/wp-json\/wp\/v2\/tags?post=2456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}